{"id":3202,"date":"2025-10-19T05:44:14","date_gmt":"2025-10-19T05:44:14","guid":{"rendered":"https:\/\/cimcfiretruck.com\/?post_type=product&#038;p=3202"},"modified":"2025-10-20T07:45:45","modified_gmt":"2025-10-20T07:45:45","slug":"wireless-control-water-supply-fire-brigade-truck-fire-fighting-vehicles-294kw","status":"publish","type":"product","link":"https:\/\/cimcfiretruck.com\/ko\/product\/wireless-control-water-supply-fire-brigade-truck-fire-fighting-vehicles-294kw\/","title":{"rendered":"Wireless Control Water Supply Fire Brigade Truck \/ Fire Fighting Vehicles 294kw"},"content":{"rendered":"<div>\n<p><span><strong>\uc2dc\uc2a4\ud15c \uad6c\uc131<\/strong><\/span><\/p>\n<p>1 Pumping Fire Truck+ 1 Hose Equipped fire truck+ 1 Equipment Fire Vehicle(Based on water supply distance determine the quantity of Hose Equipped fire truck. Based on water hose bridge and water supply equipment determine the quantity of Hose Equipment fire vehicle)<br \/>&nbsp;<\/p>\n<p><span><strong>System Function<\/strong><\/span><\/p>\n<p>1) \ud654\uc7ac \uc9c4\ud654 \uacf5\uae09, \ud654\uc7ac \ud1b5\uc81c, \uce68\uc218 \ubc30\uc218 \ubc0f \uad6c\uc870 \uae30\ub2a5 \ud3ec\ud568.<br \/>2) \uc218\uc785 \ud38c\ud504\ub294 \u2265400L\/S \ud3c9\uade0 \uc18d\ub3c4\ub85c \u226530m \uae4a\uc774\uc758 \ubb3c\uc6d0\uc5d0\uc11c \uc218\uc9c1\uc73c\ub85c \ubb3c\uc744\u62bd\u51fa\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<br \/>3) \uc2dc\uc2a4\ud15c\uc740 \uc218\ud3c9 \uc591\ucabd \ud38c\ud504 \uc791\ub3d9 \uc911 \u2265400L\/S \uc18d\ub3c4\ub85c \u22653000m\uae4c\uc9c0 \ubb3c\uc744 \uacf5\uae09\ud560 \uc218 \uc788\uc73c\uba70, \ucd5c\uc885 \ubb3c \uacf5\uae09 \uc555\ub825 \u22650.2Mpa\uc785\ub2c8\ub2e4.<br \/>4) \uc2dc\uc2a4\ud15c\uc740 \uc218\ud3c9 \ub2e8\ucabd \ud38c\ud504 \uc791\ub3d9 \uc911 \u2265200L\/S \uc18d\ub3c4\ub85c \u22655000m\uae4c\uc9c0 \ubb3c\uc744 \uacf5\uae09\ud560 \uc218 \uc788\uc73c\uba70, \ucd5c\uc885 \ubb3c \uacf5\uae09 \uc555\ub825 \u22650.2Mpa\uc785\ub2c8\ub2e4.<\/p>\n<table border=\"1\" cellpadding=\"0\" cellspacing=\"0\">\n<tbody>\n<tr>\n<td>\uc100\uc2dc \ubaa8\ub378<\/td>\n<td colspan=\"2\">ZZ5357TXFV464ME1<\/td>\n<\/tr>\n<tr>\n<td>\uc804\uccb4 \ud06c\uae30(mm)<\/td>\n<td colspan=\"2\">11800x2500x3950<\/td>\n<\/tr>\n<tr>\n<td>\ud558\uc911 \uc911\ub7c9<\/td>\n<td colspan=\"2\">33000 kg<\/td>\n<\/tr>\n<tr>\n<td>\uc5d4\uc9c4 \ubaa8\ub378 \ubc0f \ud30c\uc6cc<\/td>\n<td colspan=\"2\">MC11.40-50 294kW<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\uc218\uc785 \ubaa8\ub4c8<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">Chassis<\/td>\n<td>\uae68\uc6b0\uae30 \uc18d\ub3c4<\/td>\n<td>2.2-4.2 km\/h<\/td>\n<\/tr>\n<tr>\n<td>\ub4f1\ubc18 \ub2a5\ub825<\/td>\n<td>40%<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">Power system<\/td>\n<td>\uc5d4\uc9c4 \ubaa8\ub378<\/td>\n<td>KTA19-P750<\/td>\n<\/tr>\n<tr>\n<td>\uc5d4\uc9c4 \ucd9c\ub825<\/td>\n<td>750HP<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\">Floating pump<\/td>\n<td>\uc720\ub7c9(L\/s)<\/td>\n<td>200<\/td>\n<\/tr>\n<tr>\n<td>\uc555\ub825(Mpa)<\/td>\n<td>0.4<\/td>\n<\/tr>\n<tr>\n<td>Number<\/td>\n<td>2<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">Boom system<\/td>\n<td>\ucd5c\ub300 \uc6b4\uc601 \ubc18\uacbd<\/td>\n<td>5m<\/td>\n<\/tr>\n<tr>\n<td>\ucd5c\ub300 \ubcf4\uc774\uc5b4 \ud655\uc7a5\uc758 \ub4e4\uc5b4\uc62c\ub9bc \uc911\ub7c9<\/td>\n<td>1. 500 kg<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">Hydraulic system<\/td>\n<td>Hydraulic pump<\/td>\n<td>\n<p>\uc774\ub3d9\ub7c9\u2265180ml\/r<\/p>\n<p>\uae30\ub984 \uc555\ub825\u226535MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\uc218\uc555 \ubaa8\ud130<\/td>\n<td>\n<p>\uc774\ub3d9\ub7c9\u2265100ml\/r<\/p>\n<p>\uae30\ub984 \uc555\ub825\u226535MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Control system<\/td>\n<td colspan=\"2\">\ubb34\uc120 \uc81c\uc5b4(\uac70\ub9ac\u2265100m)+\uae34\uae09 \uc81c\uc5b4 \ubaa8\ub4dc, \ud06c\ub864\ub7ec \uc774\ub3d9, \ud48d\uc120 \ud38c\ud504 \ubb3c \uc218\uc9d1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\uc2dc\uc2a4\ud15c \uac15\ud654<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">Power system<\/td>\n<td>\uc5d4\uc9c4 \ubaa8\ub378<\/td>\n<td>KTA19-P750<\/td>\n<\/tr>\n<tr>\n<td>\uc5d4\uc9c4 \ucd9c\ub825<\/td>\n<td>750HP<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">\ubcf4\uc2a4\ud130 \ud38c\ud504<\/td>\n<td>\uc720\ub7c9(L\/s)<\/td>\n<td>400<\/td>\n<\/tr>\n<tr>\n<td>\uc555\ub825(Mpa)<\/td>\n<td>0.8<\/td>\n<\/tr>\n<tr>\n<td>Control system<\/td>\n<td colspan=\"2\">\uc2dc\uc2a4\ud15c\uc740 \ub514\uc824 \uc5d4\uc9c4\uacfc \ubb3c \ud38c\ud504\uc758 \uc791\ub3d9 \uc0c1\ud0dc\ub97c \uac10\uc9c0\ud558\uace0 \uc81c\uc5b4\ud558\uace0, \uc218\uc9d1 \ubaa8\ub4c8\uc758 \uc791\ub3d9\uc744 \ubaa8\ub2c8\ud130\ub9c1\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/td>\n<\/tr>\n<tr>\n<td>Boom system<\/td>\n<td>\ucd5c\ub300 \uc791\uc5c5 \ubc18\uacbd<\/td>\n<td>\u226517m<\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td>\ucd5c\ub300 \ubcf4\uc774\uc5b4 \ud655\uc7a5\uc758 \ub4e4\uc5b4\uc62c\ub9bc \uc911\ub7c9<\/td>\n<td>\u2265400kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/desc2\/20190806114049_25055.jpg\">&nbsp;<\/p>\n<p><span>\uc790\uc8fc \ubb3b\ub294 \uc9c8\ubb38<\/span><\/p>\n<p>1. Q: \uc65c \ub2f9\uc2e0\uc744 \uc120\ud0dd\ud574\uc57c \ud569\ub2c8\uae4c?<\/p>\n<p>&nbsp; &nbsp; A: a. \uc6b0\ub9ac\ub294 \uc0c1\ud558\uc774\uc2dc\uc5d0 \uc704\uce58\ud55c \uc18c\ubc29\ucc28 \uc81c\ud488 \uc804\ubb38 \uc81c\uc870\uc5c5\uccb4\ub85c, \ud478\ub3d9 \uad6d\uc81c\uacf5\ud56d \uadfc\ucc98\uc5d0 \uc788\uc5b4 \uace0\uac1d\uc774 \uc27d\uac8c \ubc29\ubb38\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; b. \uc6b0\ub9ac\ub294 \ud574\uc678 \uace0\uac1d\uc5d0\uac8c \uc9c1\uc811 \uc218\ucd9c\ud560 \uc218 \uc788\uc73c\uba70, \ubb34\uc5ed \ud68c\uc0ac\uc640 \uac70\ub798\ud560 \ud544\uc694\uac00 \uc5c6\uace0 \ub450 \ubc88\uc9f8 \uac00\uaca9 \uc778\uc0c1\uc774 \ubc1c\uc0dd\ud558\uc9c0 \uc54a\uc2b5\ub2c8\ub2e4.<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; c. \uc6b0\ub9ac\ub294 \uc790\uccb4 R&amp;D \ud300, \uc0dd\uc0b0 \uc791\uc5c5\uc7a5, QC \uad00\ub9ac \ud300, \uad6d\uc81c \ub9c8\ucf00\ud305 \ud300 \ubc0f \uc560\ud504\ud130 \uc11c\ube44\uc2a4 \ud300\uc744 \ubcf4\uc720\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n<p>2. Q: \ubc30\uc1a1 \uc2dc\uac04\uc740 \uc5bc\ub9c8\uc785\ub2c8\uae4c?<\/p>\n<p>&nbsp; &nbsp; A: a. \uc815\uc0c1 \ud45c\uc900 \ubaa8\ub378\uc758 \uc7ac\uace0\uac00 \uc788\uc744 \uacbd\uc6b0, \uc120\uae09\uae08\uc744 \ubc1b\uc740 \ud6c4 20\uc77c \uc774\ub0b4\uc5d0 \ubc30\uc1a1\ub429\ub2c8\ub2e4.<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;b. ISUZU \ubc0f \uc911\uad6d \ube0c\ub79c\ub4dc \uc100\uc2dc\ub294 \uc120\uae09\uae08\uc744 \ubc1b\uc740 \ud6c4 3\uac1c\uc6d4 \uc774\ub0b4\uc5d0 \ubc30\uc1a1\ub429\ub2c8\ub2e4.<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;c. \uc720\ub7fd \ube0c\ub79c\ub4dc \uc100\uc2dc\ub294 \uc120\uae09\uae08\uc744 \ubc1b\uc740 \ud6c4 9\uac1c\uc6d4 \uc774\ub0b4\uc5d0 \ubc30\uc1a1\ub429\ub2c8\ub2e4.<\/p>\n<p>3. Q:\uadc0\ud558\uc758 \uacb0\uc81c \ubc29\ubc95\uc740 \ubb34\uc5c7\uc778\uac00\uc694?<\/p>\n<p>&nbsp; &nbsp; A: T\/T\uc640 L\/C\uac00 \uc120\ud638\ub429\ub2c8\ub2e4.<\/p>\n<p>4.Q: \ucc28\ub7c9 \ubc30\uc1a1\uc744 \uc8fc\uc120\ud558\uc2dc\ub098\uc694?<\/p>\n<p>&nbsp; &nbsp;A: \ub124, \uac70\ub798 \uc870\uac74\uc5d0 \ub530\ub77c \ubc30\uc1a1\uc744 \uc8fc\uc120\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n<p>5. Q: \ud3ec\uc7a5\uc740 \uc5b4\ub5bb\uac8c \ub418\ub098\uc694?<\/p>\n<p>&nbsp; &nbsp; A: \ubaa8\ub4e0 \ud3ec\uc7a5\uc740 \uc218\ucd9c \uae30\uc900\uc744 \uc900\uc218\ud569\ub2c8\ub2e4.<\/p>\n<p><span>\ub2e4\ub978 \uc9c8\ubb38\uc774 \uc788\uc73c\uc2dc\uba74 \uc8fc\uc800\ud558\uc9c0 \ub9d0\uace0 \uc800\ud76c\uc5d0\uac8c \uc5f0\ub77d\ud574 \uc8fc\uc2ed\uc2dc\uc624.<\/span><\/p>\n<\/p><\/div>","protected":false},"excerpt":{"rendered":"<h3>\uc81c\ud488 \uc138\ubd80\uc815\ubcf4:<\/h3>\n<ul>\n<li>\n<div class=\"detail-attr\">\uc100\uc2dc \ube0c\ub79c\ub4dc<\/div>\n<div class=\"bottom-val\"> Howo <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\uc5f0\ub8cc \uc720\ud615<\/div>\n<div class=\"bottom-val\"> \ub514\uc824 <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">ARFF, fire services, aviation safety, fire apparatus, Company Two Fire<\/div>\n<div class=\"bottom-val\"> 6??4 <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\ucd5c\ub300 \ucd9c\ub825<\/div>\n<div class=\"bottom-val\"> 294kw <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\ud50c\ub85c\ud305 \ud38c\ud504<\/div>\n<div class=\"bottom-val\"> 200\u6d41\u91cf(L\/s) <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">Brake Type<\/div>\n<div class=\"bottom-val\"> ABS <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\ubcc0\uc18d\uae30<\/div>\n<div class=\"bottom-val\"> \uc218\ub3d9 12 <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\uc81c\ud488 \uc774\ub984<\/div>\n<div class=\"bottom-val\"> \ubb3c \uacf5\uae09 \ud654\uc7ac \uad6c\uc870\ub300 \ucc28\ub7c9 <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\uc6d0\uc0b0\uc9c0<\/div>\n<div class=\"bottom-val\"> \uc0c1\ud558\uc774, \uc911\uad6d <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\ube0c\ub79c\ub4dc \uc774\ub984<\/div>\n<div class=\"bottom-val\"> CIMC Jindun <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\uc778\uc99d<\/div>\n<div class=\"bottom-val\"> ISO9001, CCC <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\ubaa8\ub378 \ubc88\ud638<\/div>\n<div class=\"bottom-val\"> JDX5330TXFBP400 <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\ucd5c\uc18c \uc8fc\ubb38 \uc218\ub7c9<\/div>\n<div class=\"bottom-val\"> 1 \ub300 <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">Advanced Technologies in Fire Trucks at Denver International Airport<\/div>\n<div class=\"bottom-val\"> \ud611\uc0c1 \uac00\ub2a5 <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\ud3ec\uc7a5 \uc138\ubd80\uc815\ubcf4<\/div>\n<div class=\"bottom-val\"> \uc218\ucd9c \ud45c\uc900 \ud3ec\uc7a5 \ub610\ub294 \ub9de\ucda4 \ud3ec\uc7a5 <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\ubc30\uc1a1 \uc2dc\uac04<\/div>\n<div class=\"bottom-val\"> \uacc4\uc57d \uc11c\uba85 \ud6c4 90\uc77c <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\uc9c0\ubd88 \uc870\uac74<\/div>\n<div class=\"bottom-val\"> L\/C, D\/A, D\/P, T\/T, \uc6e8\uc2a4\ud134 \uc720\ub2c8\uc628, \uba38\ub2c8\uadf8\ub7a8 <\/div>\n<\/li>\n<li>\n<div class=\"detail-attr\">\uacf5\uae09 \ub2a5\ub825<\/div>\n<div class=\"bottom-val\"> \uc5f0\uac04 350\ub300 <\/div>\n<\/li>\n<\/ul>","protected":false},"featured_media":3290,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[44],"product_tag":[],"class_list":["post-3202","product","type-product","status-publish","has-post-thumbnail","product_cat-remote-water-supply-system-fire-truck","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-magnify-disabled","ast-product-tabs-layout-horizontal","ast-qv-on-image","first","instock","shipping-taxable","product-type-simple"],"spectra_custom_meta":{"rank_math_internal_links_processed":["1"],"_sku":["M2235"],"total_sales":["0"],"_tax_status":["taxable"],"_tax_class":[""],"_manage_stock":["no"],"_backorders":["no"],"_sold_individually":["no"],"_virtual":["no"],"_downloadable":["no"],"_download_limit":["-1"],"_download_expiry":["-1"],"_stock":[null],"_stock_status":["instock"],"_wc_average_rating":["0"],"_wc_review_count":["0"],"_product_version":["10.2.2"],"_wp_old_slug":["import-placeholder-for-464"],"_thumbnail_id":["3290"],"_product_image_gallery":["3291"],"_uag_css_file_name":["uag-css-3202.css"],"_uag_js_file_name":["uag-js-3202.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:46990:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading {background: var(--ast-global-color-5);margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: -90px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading {background: var(--ast-global-color-5);margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: -90px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-684b2d7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-684b2d7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 100%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-684b2d7b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;color: var(--ast-global-color-5);}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-b1714557.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: var(--ast-global-color-5) !important;}.uagb-block-b1714557.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b1714557.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-87580ece.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: var(--ast-global-color-5) !important;}.uagb-block-87580ece.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-87580ece.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-684b2d7b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-684b2d7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-684b2d7b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-684b2d7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-684b2d7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-684b2d7b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}\ufeff.uagb-forms__outer-wrap .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-input::placeholder,.uagb-forms__outer-wrap .uagb-forms-input-label,.uagb-forms__outer-wrap .uagb-forms-main-submit-button,.uagb-forms__outer-wrap .uagb-forms-success-message,.uagb-forms__outer-wrap .uagb-forms-failed-message{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.15s;-moz-transition-duration:.15s;-o-transition-duration:.15s;transition-duration:.15s}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]{min-height:0 !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input::-webkit-input-placeholder,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]::-webkit-input-placeholder{overflow:unset}.uagb-forms__outer-wrap .uagb-forms-main-form input:not([type=checkbox]):not([type=radio]):not([type=file]),.uagb-forms__outer-wrap .uagb-forms-main-form textarea,.uagb-forms__outer-wrap .uagb-forms-main-form select{width:100%;box-sizing:border-box}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-checkbox-wrap .uagb-form-checkbox-option input.uagb-inner-input-view{width:33%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-forms-phone-input{width:75% !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%;justify-content:space-between}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .required::after{color:red;content:\" *\"}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-form-hidden-data{display:none}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button.wp-block-button__link{width:auto}.uagb-forms__outer-wrap .uagb-forms-submit-message-hide{display:none}.uagb-forms__outer-wrap .uagb-forms-success-message{padding:20px 20px}.uagb-forms__outer-wrap .uagb-forms-failed-message{padding:20px 20px}.uagb-forms__outer-wrap span.components-spinner{float:none}.uagb-forms__outer-wrap .uagb-forms-input.uagb-form-phone-country{background-color:#fff}.uagb-forms__outer-wrap .uag-col-2-wrap{display:grid;grid-template-columns:1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-3-wrap{display:grid;grid-template-columns:1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-4-wrap{display:grid;grid-template-columns:1fr 1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uagb-switch{position:relative;display:inline-block;width:50px;height:25px}.uagb-forms__outer-wrap .uagb-switch input{width:0;height:0;opacity:0}.uagb-forms__outer-wrap .uagb-slider{position:absolute;top:0;right:0;bottom:0;left:0;background-color:#fff;cursor:pointer;transition:.4s;-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch .uagb-slider::before{position:absolute;width:20px;height:20px;background-color:#000;transition:.4s;content:\"\";-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch input:checked+.uagb-slider::before{background-color:#fff}.uagb-forms__outer-wrap .uagb-slider.round::before{border-radius:50% !important}.uagb-forms-select-box,.uagb-form-phone-country,.uagb-forms-phone-wrap .uagb-forms-phone-input{height:auto;-webkit-appearance:none;appearance:none}.uagb-forms-radio-wrap input[type=radio]:checked+label::before{line-height:1.2;content:\" \"}.uagb-forms-radio-wrap input[type=radio]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\"\"}.uagb-forms-radio-wrap input[type=radio].round+label::before{border-radius:100% !important}select::after,select::before{padding:10px}.uagb-forms-radio-wrap input[type=radio],.uagb-forms-checkbox-wrap input[type=checkbox],.uagb-forms-accept-wrap input[type=checkbox]{opacity:0}.uagb-forms-checkbox-wrap input[type=checkbox]:checked+label::before,.uagb-forms-accept-wrap input[type=checkbox]:checked+label::before{line-height:1.2;content:\"\u2714\"}.uagb-forms-checkbox-wrap input[type=checkbox]+label::before,.uagb-forms-accept-wrap input[type=checkbox]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\" \"}@media only screen and (max-width: 767px){.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%}}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-20 .uagb-forms-main-form{column-gap:20px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-15 .uagb-forms-main-form{column-gap:15px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-10 .uagb-forms-main-form{column-gap:10px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-5 .uagb-forms-main-form{column-gap:5px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-flex-start .uagb-forms-main-form{align-items:flex-start}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-center .uagb-forms-main-form{align-items:center}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form{display:flex;flex-wrap:wrap;margin:0 -5px;position:relative;text-align:left}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-80{width:80%}@media(min-width: 768px)and (max-width: 1024px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}@media(max-width: 767px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dc93bae9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dc93bae9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 100%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dc93bae9{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-5b07ee25.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5b07ee25 .uagb-forms-main-form textarea{text-align: left;}.uagb-block-5b07ee25 .uagb-forms-input{text-align: left;}.uagb-block-5b07ee25 .uagb-forms-input-label{display: block;text-align: left;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-field-set{margin-bottom: 20px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input:focus{outline:  none !important;background-color:  !important;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input:focus::placeholder{color:  !important;}.uagb-block-5b07ee25 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-5b07ee25 .uagb-form-phone-country{background: url(data:image\/svg+xmlbase64,PHN2ZyB2aWV3Qm94PSIwIDAgNTEyIDUxMiIgd2lkdGg9JzE4cHgnIGhlaWdodD0nMThweCcgeG1sOnNwYWNlPSJwcmVzZXJ2ZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiBlbmFibGUtYmFja2dyb3VuZD0ibmV3IDAgMCA1MTIgNTEyIj48cGF0aCBkPSJtMzk2LjYgMTYwIDE5LjQgMjAuN0wyNTYgMzUyIDk2IDE4MC43bDE5LjMtMjAuN0wyNTYgMzEwLjV6IiBmaWxsPSIjMWQyMzI3IiBjbGFzcz0iZmlsbC0wMDAwMDAiPjwvcGF0aD48L3N2Zz4=) no-repeat;-moz-appearance: none !important;-webkit-appearance:  none !important;background-position:  top 50% right 12px;appearance: none !important;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-5b07ee25 .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-5b07ee25 .uagb-forms-radio-wrap input[type=radio] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-5b07ee25 .uagb-slider{background-color: #ffffff;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider:before{height: 20px;width: 20px;top: 3px;bottom: 3px;left: 3px;background-color: #1e1e1e;border-radius: 3px 3px 3px 3px;}.uagb-block-5b07ee25 .uagb-switch input:checked + .uagb-slider{background-color: #017cba;}.uagb-block-5b07ee25 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);background-color: #ffffff;}.uagb-block-5b07ee25 .uagb-switch input:focus + .uagb-slider{box-shadow: 0 0 1px#017cba;}.uagb-block-5b07ee25 .uagb-forms-accept-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input.uagb-form-phone-country{padding-top: 11px;padding-bottom: 11px;padding-left: 12px;padding-right: 12px;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-input{padding-top: 12px;padding-bottom: 12px;padding-left: 12px;padding-right: 12px;}.uagb-block-5b07ee25 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{background-color: #ffffff;box-shadow: inset 0 0 0 4px #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap.wp-block-button:not(.is-style-outline) .uagb-forms-main-submit-button.wp-block-button__link {font-size: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button {font-size: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-5b07ee25.uagb-forms__full-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{width: 100%;padding: 10px 15px;}.uagb-block-5b07ee25.uagb-forms__small-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 5px 10px;}.uagb-block-5b07ee25.uagb-forms__medium-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 12px 24px;}.uagb-block-5b07ee25.uagb-forms__large-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 20px 30px;}.uagb-block-5b07ee25.uagb-forms__extralarge-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 30px 65px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dc93bae9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dc93bae9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dc93bae9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-5b07ee25.uagb-forms__outer-wrap{padding-top: 25px;padding-right: 25px;padding-bottom: 25px;padding-left: 25px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-5b07ee25 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-5b07ee25 .uagb-form-phone-country{background-position: top 50% right 12px;padding-right: 30px;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-5b07ee25 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dc93bae9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dc93bae9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dc93bae9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-5b07ee25.uagb-forms__outer-wrap{padding-top: 25px;padding-right: 25px;padding-bottom: 25px;padding-left: 25px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-5b07ee25 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-5b07ee25 .uagb-form-phone-country{background-position: top 50% right 6px;padding-right: 30px;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-5b07ee25 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c06e47bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c06e47bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 100%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c06e47bb{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;color: var(--ast-global-color-5);}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-6d307ac1.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-bfb40a34.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-bfb40a34.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-be5c3101.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-be5c3101.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c06e47bb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c06e47bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c06e47bb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-6d307ac1.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c06e47bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c06e47bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c06e47bb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-6d307ac1.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}\";s:2:\"js\";s:564:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBForms.init( {\"block_id\":\"5b07ee25\",\"reCaptchaEnable\":false,\"reCaptchaType\":\"v2\",\"reCaptchaSiteKeyV2\":\"\",\"reCaptchaSiteKeyV3\":\"\",\"afterSubmitToEmail\":\"\",\"afterSubmitCcEmail\":\"\",\"afterSubmitBccEmail\":\"\",\"afterSubmitEmailSubject\":\"Form Submission\",\"sendAfterSubmitEmail\":true,\"confirmationType\":\"message\",\"hidereCaptchaBatch\":false,\"captchaMessage\":\"Please fill up the above captcha.\",\"confirmationUrl\":\"\"}, '.uagb-block-5b07ee25', 3202 );\n});\n });\";s:18:\"current_block_list\";a:18:{i:0;s:11:\"core\/search\";i:1;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:17:\"core\/latest-posts\";i:4;s:20:\"core\/latest-comments\";i:5;s:13:\"core\/archives\";i:6;s:15:\"core\/categories\";i:8;s:21:\"uagb\/advanced-heading\";i:9;s:30:\"woocommerce\/product-categories\";i:10;s:12:\"core\/columns\";i:11;s:11:\"core\/column\";i:12;s:9:\"core\/html\";i:13;s:14:\"uagb\/container\";i:14;s:14:\"uagb\/icon-list\";i:15;s:20:\"uagb\/icon-list-child\";i:17;s:10:\"uagb\/forms\";i:18;s:16:\"uagb\/forms-email\";i:19;s:14:\"core\/tag-cloud\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1788333197;s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235.webp",702,502,false],"thumbnail":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235-150x150.webp",150,150,true],"medium":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235-300x215.webp",300,215,true],"medium_large":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235.webp",702,502,false],"large":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235.webp",702,502,false],"1536x1536":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235.webp",702,502,false],"2048x2048":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235.webp",702,502,false],"trp-custom-language-flag":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235.webp",18,12,false],"woocommerce_thumbnail":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235-385x275.webp",385,275,true],"woocommerce_single":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235.webp",702,502,false],"woocommerce_gallery_thumbnail":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M2235-100x100.webp",100,100,true]},"uagb_author_info":{"display_name":"info@cimcfiretruck.com","author_link":"https:\/\/cimcfiretruck.com\/ko\/blog\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Product Details: Chassis Brand Howo Fuel Type Diesel Drive Type 6??4 Max. Power 294kw Floating Pump 200 Flow(L\/s) Brake Type ABS Transmission Manual 12 Product Name Water Supply Fire Brigade Vehicle Place of Origin SHANGHAI,CHINA Brand Name CIMC Jindun Certification ISO9001,CCC Model Number JDX5330TXFBP400 Minimum Order Quantity 1 unit Price Negotiable Packaging Details Exporting standard&hellip;","_links":{"self":[{"href":"https:\/\/cimcfiretruck.com\/ko\/wp-json\/wp\/v2\/product\/3202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cimcfiretruck.com\/ko\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cimcfiretruck.com\/ko\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cimcfiretruck.com\/ko\/wp-json\/wp\/v2\/comments?post=3202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cimcfiretruck.com\/ko\/wp-json\/wp\/v2\/media\/3290"}],"wp:attachment":[{"href":"https:\/\/cimcfiretruck.com\/ko\/wp-json\/wp\/v2\/media?parent=3202"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cimcfiretruck.com\/ko\/wp-json\/wp\/v2\/product_brand?post=3202"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cimcfiretruck.com\/ko\/wp-json\/wp\/v2\/product_cat?post=3202"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cimcfiretruck.com\/ko\/wp-json\/wp\/v2\/product_tag?post=3202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}