{"id":1842,"date":"2025-10-19T05:30:51","date_gmt":"2025-10-19T05:30:51","guid":{"rendered":"https:\/\/cimcfiretruck.com\/?post_type=product&#038;p=1842"},"modified":"2025-10-20T07:44:42","modified_gmt":"2025-10-20T07:44:42","slug":"car-moving-robot-for-lifting-cars-automatically-for-emergency-rescue","status":"publish","type":"product","link":"https:\/\/cimcfiretruck.com\/vi\/san-pham\/car-moving-robot-for-lifting-cars-automatically-for-emergency-rescue\/","title":{"rendered":"Car-Moving Robot for Lifting Cars Automatically for Emergency Rescue"},"content":{"rendered":"<table width=\"100%\" border=\"0\" class=\"tab1\">\n<tbody>\n<tr>\n<td colspan=\"4\">\n<p class=\"title\" id=\"detail_infomation\">Th\u00f4ng tin chi ti\u1ebft<\/p>\n<\/td>\n<\/tr>\n<tr>\n<th title=\"\u1ee8ng d\u1ee5ng::\">\u1ee8ng d\u1ee5ng:<\/th>\n<td title=\"Government Departments, Traffic Police, Fire Rescue, Property Security, Public Transportation Etc.:\">Government Departments, Traffic Police, Fire Rescue, Property Security, Public Transportation Etc.<\/td>\n<th title=\"K\u00edch th\u01b0\u1edbc::\">K\u00edch th\u01b0\u1edbc:<\/th>\n<td title=\"1370mm*1100mm*140mm:\">1370mm*1100mm*140mm<\/td>\n<\/tr>\n<tr>\n<th title=\"Mass::\">Mass:<\/th>\n<td title=\"140kg:\">140kg<\/td>\n<th title=\"Moving Speed::\">Moving Speed:<\/th>\n<td title=\"60s:\">60s<\/td>\n<\/tr>\n<tr>\n<th title=\"Gear Position::\">Gear Position:<\/th>\n<td title=\"Three Gear Shift:\">Three Gear Shift<\/td>\n<th title=\"Gradeability::\">Gradeability:<\/th>\n<td title=\"&lt;15 Degrees:\">&lt;15 Degrees<\/td>\n<\/tr>\n<tr>\n<th title=\"Max. Lifting Height::\">Max. Lifting Height:<\/th>\n<td title=\"??500mm:\">??500mm<\/td>\n<th title=\"Max. Lifting Load::\">Max. Lifting Load:<\/th>\n<td title=\"??2600kg:\">??2600kg<\/td>\n<\/tr>\n<tr>\n<th colspan=\"1\" title=\"Max. Lifting Load::\">N\u1ed5i B\u1eadt:<\/th>\n<td colspan=\"3\" title=\"??2600kg:\">\n<h2 style='display: inline-block;font-weight: bold;font-size: 14px;'>140kg Car-Moving Robot<\/h2>\n<p>, <\/p>\n<h2 style='display: inline-block;font-weight: bold;font-size: 14px;'>CE Car-Moving Robot<\/h2>\n<p>, <\/p>\n<h2 style='display: inline-block;font-weight: bold;font-size: 14px;'>CXFIRE Car-Moving Robot<\/h2>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"split-xx\"><\/div>\n<section>\n<p><span><span><strong>1. Product Name:<\/strong> Car-Moving Robot<\/span><\/span><\/p>\n<p><span><strong><span>2. Main Application<\/span><\/strong><\/span><\/p>\n<p><span><span>2.1 This robot is more suitable for: government departments, traffic police, fire rescue, property security, public transportation and other enterprises and institutions to clear obstacles and regulate parking tools, and it is also the most powerful helper for heavy object handling.<br \/>2.2 Small size, lightweight, high strength, wide application, intelligent and reliable, flexible and diverse operation. While effectively helping the parking lot to increase the car capacity, it also solves the trouble of car owners waiting for the car to move.<\/span><\/span><\/p>\n<p><span><strong><span>3. Main Advantages<\/span><\/strong><\/span><\/p>\n<p><span><span>3.1 Smart: Intelligent 360-degree imaging, multiple detectors and sensing probes, intelligently determine the surrounding environment and respond and prompt, thereby assisting the safe return of the vehicle and avoiding various accidents.<br \/>3.2 Efficient: Narrow parking front and rear, side parking, corner parking, and leaving the car at one time, no need to wait for a long time, easily move the car in a few seconds.<br \/>3.3 Advanced: Mobile APP visualized remote control operation, which can move at a constant speed in four directions, front, back, left, and right, 360-degree U-turn, simple and stable operation.<br \/>3.4 Standardization: Standardize road traffic management, maintain parking order, ensure vehicle orientation and parking distance, and make disorderly parking standardized and tidy.<\/span><\/span><\/p>\n<p><span><strong><span>4. Datasheet<\/span><\/strong><\/span><\/p>\n<p><span><span>4.1 Dimensions: 1370mm*1100mm*140mm<br \/>4.2 Mass: 140kg<br \/>4.3 Moving speed: \u226460s<br \/>4.4 Gear position: three gear shift<br \/>4.5 Gradeability: &lt;15 degrees<br \/>4.6 Adapt to the ground: \u00b115mm\/M<br \/>4.7 Battery monitoring: power display<br \/>4.8Turning radius: 360 degrees in place<br \/>4.9Turning method: differential steering<br \/>4.10 Mechanical power: 2X300W<br \/>4.11 Battery: 48V, charging time: \u22644 hours<br \/>4.12 Walking battery life \u2265 2 hours<br \/>4.13 Maximum lifting height: \u2264500mm<br \/>4.14 Maximum lifting load: \u22642600kg<br \/>4.15 Remote control range: within 30M in diameter<\/span><\/span><\/p>\n<div><span><\/span><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<h3>Chi ti\u1ebft s\u1ea3n ph\u1ea9m:<\/h3>\n<table class=\"tables data\" width=\"100%\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\">\n<tbody>\n<tr>\n<td class=\"p_name\">N\u01a1i xu\u1ea5t x\u1ee9:<\/td>\n<td class=\"p_attribute\">Trung Qu\u1ed1c<\/td>\n<\/tr>\n<tr>\n<td class=\"p_name\">T\u00ean th\u01b0\u01a1ng hi\u1ec7u:<\/td>\n<td class=\"p_attribute\">brush fire trucks, wildland firefighting, fire safety equipment, off-road fire trucks, firefighting technology, business safety, emergency response vehicles<\/td>\n<\/tr>\n<tr>\n<td class=\"p_name\">Ch\u1ee9ng nh\u1eadn:<\/td>\n<td class=\"p_attribute\">CCC, CE, EN, NFPA<\/td>\n<\/tr>\n<tr>\n<td class=\"p_name\">S\u1ed1 m\u00f4 h\u00ecnh:<\/td>\n<td class=\"p_attribute\">CMR<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3 style=\"margin-top: 20px;\">\u0110i\u1ec1u kho\u1ea3n thanh to\u00e1n &amp; giao h\u00e0ng:<\/h3>\n<table class=\"tables data\" width=\"100%\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\">\n<tbody>\n<tr>\n<th class=\"p_name\">S\u1ed1 l\u01b0\u1ee3ng \u0111\u1eb7t h\u00e0ng t\u1ed1i thi\u1ec3u:<\/th>\n<td class=\"p_attribute\">1 \u0110\u01a1n V\u1ecb<\/td>\n<\/tr>\n<tr>\n<th class=\"p_name\">Gi\u00e1:<\/th>\n<td class=\"p_attribute\">USD15000-USD20000<\/td>\n<\/tr>\n<tr>\n<th class=\"p_name\">Chi ti\u1ebft \u0111\u00f3ng g\u00f3i:<\/th>\n<td class=\"p_attribute\">G\u00f3i Xu\u1ea5t Kh\u1ea9u Ti\u00eau Chu\u1ea9n v\u00e0 Giao H\u00e0ng B\u1eb1ng T\u00e0u ho\u1eb7c M\u00e1y Bay<\/td>\n<\/tr>\n<tr>\n<th class=\"p_name\">Th\u1eddi gian giao h\u00e0ng:<\/th>\n<td class=\"p_attribute\">2-3 months<\/td>\n<\/tr>\n<tr>\n<th class=\"p_name\">\u0110i\u1ec1u kho\u1ea3n thanh to\u00e1n:<\/th>\n<td class=\"p_attribute\">T\/T, L\/C, D\/A, D\/P<\/td>\n<\/tr>\n<tr>\n<th class=\"p_name\">Kh\u1ea3 n\u0103ng cung c\u1ea5p:<\/th>\n<td class=\"p_attribute\">1000 \u0111\u01a1n v\u1ecb m\u1ed7i n\u0103m<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"featured_media":1893,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":["post-1842","product","type-product","status-publish","has-post-thumbnail","product_cat-fire-extinguishing-robot","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-magnify-disabled","ast-product-tabs-layout-horizontal","ast-qv-on-image","first","instock","shipping-taxable","product-type-simple"],"spectra_custom_meta":{"rank_math_internal_links_processed":["1"],"_sku":["M1092"],"total_sales":["0"],"_tax_status":["taxable"],"_tax_class":[""],"_manage_stock":["no"],"_backorders":["no"],"_sold_individually":["no"],"_virtual":["no"],"_downloadable":["no"],"_download_limit":["-1"],"_download_expiry":["-1"],"_stock":[null],"_stock_status":["instock"],"_wc_average_rating":["0"],"_wc_review_count":["0"],"_product_version":["10.2.2"],"_wp_old_slug":["import-placeholder-for-92"],"_thumbnail_id":["1893"],"_product_image_gallery":["1894"],"_uag_css_file_name":["uag-css-1842.css"],"_uag_js_file_name":["uag-js-1842.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:46990:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading {background: var(--ast-global-color-5);margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: -90px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading {background: var(--ast-global-color-5);margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: -90px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-51bdfdd2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-684b2d7b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-684b2d7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-684b2d7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 100%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-684b2d7b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;color: var(--ast-global-color-5);}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-b1714557.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: var(--ast-global-color-5) !important;}.uagb-block-b1714557.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b1714557.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-87580ece.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: var(--ast-global-color-5) !important;}.uagb-block-87580ece.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-87580ece.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-684b2d7b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-684b2d7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-684b2d7b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-684b2d7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-684b2d7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-684b2d7b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-a32bfd6f.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}\ufeff.uagb-forms__outer-wrap .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-input::placeholder,.uagb-forms__outer-wrap .uagb-forms-input-label,.uagb-forms__outer-wrap .uagb-forms-main-submit-button,.uagb-forms__outer-wrap .uagb-forms-success-message,.uagb-forms__outer-wrap .uagb-forms-failed-message{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.15s;-moz-transition-duration:.15s;-o-transition-duration:.15s;transition-duration:.15s}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]{min-height:0 !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input::-webkit-input-placeholder,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]::-webkit-input-placeholder{overflow:unset}.uagb-forms__outer-wrap .uagb-forms-main-form input:not([type=checkbox]):not([type=radio]):not([type=file]),.uagb-forms__outer-wrap .uagb-forms-main-form textarea,.uagb-forms__outer-wrap .uagb-forms-main-form select{width:100%;box-sizing:border-box}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-checkbox-wrap .uagb-form-checkbox-option input.uagb-inner-input-view{width:33%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-forms-phone-input{width:75% !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%;justify-content:space-between}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .required::after{color:red;content:\" *\"}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-form-hidden-data{display:none}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button.wp-block-button__link{width:auto}.uagb-forms__outer-wrap .uagb-forms-submit-message-hide{display:none}.uagb-forms__outer-wrap .uagb-forms-success-message{padding:20px 20px}.uagb-forms__outer-wrap .uagb-forms-failed-message{padding:20px 20px}.uagb-forms__outer-wrap span.components-spinner{float:none}.uagb-forms__outer-wrap .uagb-forms-input.uagb-form-phone-country{background-color:#fff}.uagb-forms__outer-wrap .uag-col-2-wrap{display:grid;grid-template-columns:1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-3-wrap{display:grid;grid-template-columns:1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-4-wrap{display:grid;grid-template-columns:1fr 1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uagb-switch{position:relative;display:inline-block;width:50px;height:25px}.uagb-forms__outer-wrap .uagb-switch input{width:0;height:0;opacity:0}.uagb-forms__outer-wrap .uagb-slider{position:absolute;top:0;right:0;bottom:0;left:0;background-color:#fff;cursor:pointer;transition:.4s;-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch .uagb-slider::before{position:absolute;width:20px;height:20px;background-color:#000;transition:.4s;content:\"\";-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch input:checked+.uagb-slider::before{background-color:#fff}.uagb-forms__outer-wrap .uagb-slider.round::before{border-radius:50% !important}.uagb-forms-select-box,.uagb-form-phone-country,.uagb-forms-phone-wrap .uagb-forms-phone-input{height:auto;-webkit-appearance:none;appearance:none}.uagb-forms-radio-wrap input[type=radio]:checked+label::before{line-height:1.2;content:\" \"}.uagb-forms-radio-wrap input[type=radio]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\"\"}.uagb-forms-radio-wrap input[type=radio].round+label::before{border-radius:100% !important}select::after,select::before{padding:10px}.uagb-forms-radio-wrap input[type=radio],.uagb-forms-checkbox-wrap input[type=checkbox],.uagb-forms-accept-wrap input[type=checkbox]{opacity:0}.uagb-forms-checkbox-wrap input[type=checkbox]:checked+label::before,.uagb-forms-accept-wrap input[type=checkbox]:checked+label::before{line-height:1.2;content:\"\u2714\"}.uagb-forms-checkbox-wrap input[type=checkbox]+label::before,.uagb-forms-accept-wrap input[type=checkbox]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\" \"}@media only screen and (max-width: 767px){.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%}}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-20 .uagb-forms-main-form{column-gap:20px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-15 .uagb-forms-main-form{column-gap:15px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-10 .uagb-forms-main-form{column-gap:10px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-5 .uagb-forms-main-form{column-gap:5px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-flex-start .uagb-forms-main-form{align-items:flex-start}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-center .uagb-forms-main-form{align-items:center}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form{display:flex;flex-wrap:wrap;margin:0 -5px;position:relative;text-align:left}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-80{width:80%}@media(min-width: 768px)and (max-width: 1024px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}@media(max-width: 767px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dc93bae9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dc93bae9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dc93bae9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 100%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dc93bae9{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-5b07ee25.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5b07ee25 .uagb-forms-main-form textarea{text-align: left;}.uagb-block-5b07ee25 .uagb-forms-input{text-align: left;}.uagb-block-5b07ee25 .uagb-forms-input-label{display: block;text-align: left;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-field-set{margin-bottom: 20px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input:focus{outline:  none !important;background-color:  !important;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input:focus::placeholder{color:  !important;}.uagb-block-5b07ee25 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-5b07ee25 .uagb-form-phone-country{background: url(data:image\/svg+xmlbase64,PHN2ZyB2aWV3Qm94PSIwIDAgNTEyIDUxMiIgd2lkdGg9JzE4cHgnIGhlaWdodD0nMThweCcgeG1sOnNwYWNlPSJwcmVzZXJ2ZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiBlbmFibGUtYmFja2dyb3VuZD0ibmV3IDAgMCA1MTIgNTEyIj48cGF0aCBkPSJtMzk2LjYgMTYwIDE5LjQgMjAuN0wyNTYgMzUyIDk2IDE4MC43bDE5LjMtMjAuN0wyNTYgMzEwLjV6IiBmaWxsPSIjMWQyMzI3IiBjbGFzcz0iZmlsbC0wMDAwMDAiPjwvcGF0aD48L3N2Zz4=) no-repeat;-moz-appearance: none !important;-webkit-appearance:  none !important;background-position:  top 50% right 12px;appearance: none !important;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-5b07ee25 .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-5b07ee25 .uagb-forms-radio-wrap input[type=radio] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-5b07ee25 .uagb-slider{background-color: #ffffff;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider:before{height: 20px;width: 20px;top: 3px;bottom: 3px;left: 3px;background-color: #1e1e1e;border-radius: 3px 3px 3px 3px;}.uagb-block-5b07ee25 .uagb-switch input:checked + .uagb-slider{background-color: #017cba;}.uagb-block-5b07ee25 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);background-color: #ffffff;}.uagb-block-5b07ee25 .uagb-switch input:focus + .uagb-slider{box-shadow: 0 0 1px#017cba;}.uagb-block-5b07ee25 .uagb-forms-accept-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input.uagb-form-phone-country{padding-top: 11px;padding-bottom: 11px;padding-left: 12px;padding-right: 12px;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-input{padding-top: 12px;padding-bottom: 12px;padding-left: 12px;padding-right: 12px;}.uagb-block-5b07ee25 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{background-color: #ffffff;box-shadow: inset 0 0 0 4px #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap.wp-block-button:not(.is-style-outline) .uagb-forms-main-submit-button.wp-block-button__link {font-size: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button {font-size: 15px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;}.uagb-block-5b07ee25.uagb-forms__full-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{width: 100%;padding: 10px 15px;}.uagb-block-5b07ee25.uagb-forms__small-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 5px 10px;}.uagb-block-5b07ee25.uagb-forms__medium-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 12px 24px;}.uagb-block-5b07ee25.uagb-forms__large-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 20px 30px;}.uagb-block-5b07ee25.uagb-forms__extralarge-btn .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button{padding: 30px 65px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dc93bae9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dc93bae9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dc93bae9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-5b07ee25.uagb-forms__outer-wrap{padding-top: 25px;padding-right: 25px;padding-bottom: 25px;padding-left: 25px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-5b07ee25 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-5b07ee25 .uagb-form-phone-country{background-position: top 50% right 12px;padding-right: 30px;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-5b07ee25 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-dc93bae9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dc93bae9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dc93bae9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-5b07ee25.uagb-forms__outer-wrap{padding-top: 25px;padding-right: 25px;padding-bottom: 25px;padding-left: 25px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-5b07ee25 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-5b07ee25 .uagb-form-phone-country{background-position: top 50% right 6px;padding-right: 30px;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #BDBDBD;}.uagb-block-5b07ee25 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-5b07ee25 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}.uagb-block-5b07ee25 .uagb-forms-main-form .uagb-forms-main-submit-button{font-size: 15px;}}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c06e47bb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c06e47bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c06e47bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 100%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c06e47bb{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;color: var(--ast-global-color-5);}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-6d307ac1.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-bfb40a34.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-bfb40a34.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-be5c3101.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-be5c3101.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c06e47bb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c06e47bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c06e47bb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-6d307ac1.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c06e47bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c06e47bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c06e47bb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-6d307ac1 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-6d307ac1.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}\";s:2:\"js\";s:565:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBForms.init( {\"block_id\":\"5b07ee25\",\"reCaptchaEnable\":false,\"reCaptchaType\":\"v2\",\"reCaptchaSiteKeyV2\":\"\",\"reCaptchaSiteKeyV3\":\"\",\"afterSubmitToEmail\":\"\",\"afterSubmitCcEmail\":\"\",\"afterSubmitBccEmail\":\"\",\"afterSubmitEmailSubject\":\"Form Submission\",\"sendAfterSubmitEmail\":true,\"confirmationType\":\"message\",\"hidereCaptchaBatch\":false,\"captchaMessage\":\"Please fill up the above captcha.\",\"confirmationUrl\":\"\"}, '.uagb-block-5b07ee25', false );\n});\n });\";s:18:\"current_block_list\";a:18:{i:0;s:11:\"core\/search\";i:1;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:17:\"core\/latest-posts\";i:4;s:20:\"core\/latest-comments\";i:5;s:13:\"core\/archives\";i:6;s:15:\"core\/categories\";i:8;s:21:\"uagb\/advanced-heading\";i:9;s:30:\"woocommerce\/product-categories\";i:10;s:12:\"core\/columns\";i:11;s:11:\"core\/column\";i:12;s:9:\"core\/html\";i:13;s:14:\"uagb\/container\";i:14;s:14:\"uagb\/icon-list\";i:15;s:20:\"uagb\/icon-list-child\";i:17;s:10:\"uagb\/forms\";i:18;s:16:\"uagb\/forms-email\";i:19;s:14:\"core\/tag-cloud\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1788333197;s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092.webp",560,400,false],"thumbnail":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092-150x150.webp",150,150,true],"medium":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092-300x214.webp",300,214,true],"medium_large":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092.webp",560,400,false],"large":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092.webp",560,400,false],"1536x1536":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092.webp",560,400,false],"2048x2048":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092.webp",560,400,false],"trp-custom-language-flag":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092.webp",18,12,false],"woocommerce_thumbnail":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092-385x275.webp",385,275,true],"woocommerce_single":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092.webp",560,400,false],"woocommerce_gallery_thumbnail":["https:\/\/cimcfiretruck.com\/wp-content\/uploads\/2025\/10\/M1092-100x100.webp",100,100,true]},"uagb_author_info":{"display_name":"info@cimcfiretruck.com","author_link":"https:\/\/cimcfiretruck.com\/vi\/blog\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Product Details: Place of Origin: China Brand Name: CXFIRE Certification: CCC, CE, EN, NFPA Model Number: CMR Payment & Shipping Terms: Minimum Order Quantity: 1 Unit Price: USD15000-USD20000 Packaging Details: Standard Export Package and Delivery by Ship or Air Delivery Time: 2-3 months Payment Terms: T\/T, L\/C, D\/A, D\/P Supply Ability: 1000 units per year","_links":{"self":[{"href":"https:\/\/cimcfiretruck.com\/vi\/wp-json\/wp\/v2\/product\/1842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cimcfiretruck.com\/vi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cimcfiretruck.com\/vi\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cimcfiretruck.com\/vi\/wp-json\/wp\/v2\/comments?post=1842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cimcfiretruck.com\/vi\/wp-json\/wp\/v2\/media\/1893"}],"wp:attachment":[{"href":"https:\/\/cimcfiretruck.com\/vi\/wp-json\/wp\/v2\/media?parent=1842"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cimcfiretruck.com\/vi\/wp-json\/wp\/v2\/product_brand?post=1842"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cimcfiretruck.com\/vi\/wp-json\/wp\/v2\/product_cat?post=1842"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cimcfiretruck.com\/vi\/wp-json\/wp\/v2\/product_tag?post=1842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}